{"id":981,"date":"2024-01-06T15:55:47","date_gmt":"2024-01-06T15:55:47","guid":{"rendered":"https:\/\/www.heli-x.info\/cms\/de\/?p=981"},"modified":"2024-01-06T15:55:47","modified_gmt":"2024-01-06T15:55:47","slug":"15-jahre-heli-x","status":"publish","type":"post","link":"https:\/\/www.heli-x.info\/cms\/de\/2024\/01\/06\/15-jahre-heli-x\/","title":{"rendered":"15 Jahre HELI-X"},"content":{"rendered":"\n<p>Erst einmal alles Gute im neuen Jahr! Das Jubil\u00e4umsjahr 2023 mit 15 Jahren HELI-X ist zu Ende gegangen. Darum hier nochmal die HELI-X Story in einem St\u00fcck:<\/p>\n\n\n\n<p><strong>2008-2011:<\/strong><\/p>\n\n\n\n<p>Die HELI-X-Story beginnt im Jahr 2007. Bei den Munich Heli Masters wurden erste Kontakte gekn\u00fcpft, und die Idee f\u00fcr den Simulator pr\u00e4sentiert. Hier wurden auch erste Unterst\u00fctzer f\u00fcr das Projekt gefunden: Markus Schaack, Marc Trautmann, Volker Desinger, Thomas B\u00f6seler.<\/p>\n\n\n\n<p>Vor allem Thomas hat mir sehr geholfen, die erste Physik-Engine zu entwickeln. Er hat eine unendliche Geduld und eine grosse F\u00e4higkeit, die Aerodynamik von Helikoptern zu analysieren. Sp\u00e4ter kamen dann Markus Siering und Sebastian Zajonz dazu. Von Sebastian stammt \u00fcbrigens das erste Helikopter-Modell in HELI-X.<\/p>\n\n\n\n<p>Zu Beginn des Jahres 2008 wurde dann die Version 0.9 ver\u00f6ffentlicht, Ende 2008 dann das erste Release, Version 1.0.<\/p>\n\n\n\n<p>Es kamen immer mehr Helfer dazu: Silke Kustermann hat das Bild f\u00fcr den Splashscreen in \u00d6l gemalt, Gerhard Klauser, Klaus Stangl und Martin Bestgen haben die ersten User-Modelle beigetragen.<\/p>\n\n\n\n<p>Bei den Szenen haben sich zu dieser Zeit vor allem Klaus Treichler und Harald Bendschneider verdient gemacht. Von Klaus stammt \u00fcbrigens die Szene &#8220;Dietersdorf&#8221;, die viele Jahre lang die Standard-Szene in HELI-X war.<\/p>\n\n\n\n<p>Als mit den Jahren die Computer leistungsf\u00e4higer wurden, und auch Szenen mit einer h\u00f6heren Aufl\u00f6sung m\u00f6glich wurden, musste nat\u00fcrlich eine neue Standard-Szene her. Aber wir m\u00fcssen unbedingt einmal eine neue Szene Dietersdorf mit den aktuellen M\u00f6glichkeiten erstellen!<\/p>\n\n\n\n<p>Im Jahr 2009 erschien dann Version 1.1, die als Neuerungen den Multiplayer und Indoor-Szenen hatte. Sie lief auch schon auf Macs mit Power-PC-Prozessoren und Intel-Prozessoren, die damals eine Neuerung bei Apple waren.<\/p>\n\n\n\n<p>Zu dieser Zeit ging es auch los mit den Speed-Helis. Ich bin immer noch stolz, dass HELI-X der erste Simulator war, der den ThreeDee-Rigid von Henseleit als Modell hatte. Wadim Wall hat damals das Modell generiert, und damit man die damals lieferbaren Farben im Simulator ausprobieren konnte, wurde der Farb- und Texturwechel implementiert.<\/p>\n\n\n\n<p>Zu dieser Zeit begann auch die Zusammenarbeit mit Mikado und Ulrich R\u00f6hr. So war es m\u00f6glich, die V-Stabi-Konfigurationsfiles in HELI-X einzulesen.<\/p>\n\n\n\n<p>Seit dem Jahr 2010 haben sich dann Rolf Rohner und Reiner Stein sehr f\u00fcr HELI-X engagiert. Aus dieser Zeit stammen die Rotorbl\u00e4tter, deren Darstellung abh\u00e4ngig vom Einstellwinkel der Bl\u00e4tter und dem Winkel zur Sonne ist, sowie das Plugin-Interface. Man konnte mit HELI-X externe Programme steueren, z.B. einen Editor f\u00fcr die Modellparameter, den Reiner geschrieben hatte. Seit dieser Zeit gibt es auch Crash-Objekte in den fotorealistischen Szenen und auch die ersten 3d-Szenen.<\/p>\n\n\n\n<p>Tomas Jedrzejek hat das User Interface ins Tschechische \u00fcbersetzt.<\/p>\n\n\n\n<p>Im Jahr 2011 kamen viele neue Szenen in einer fantastischen Qualit\u00e4t dazu. Daf\u00fcr ist Paul D\u00fcrr und Martin Koall zu danken. Seit dieser Zeit arbeite ich auch sehr gerne mit Martin Wycisk zusammen, ein grossartiger Pilot, der bei den Einstellungen von vielen, vielen Helis stark unterst\u00fctzt hat. Martin erz\u00e4hlt immer noch, dass er einen Grossteil seiner Jugend in Dietersdorf (also im Simulator HELI-X) verbracht hatte. Er war auch sehr entt\u00e4uscht, dass Dietersdorf als Standard-Szene nun mit dem Platz von Almere ersetzt wurde.<\/p>\n\n\n\n<p><strong>2012-2019:<\/strong><\/p>\n\n\n\n<p>Ein Grosser Schritt f\u00fcr HELI-X geschah im Jahr 2015. F\u00fcr die Version 5.0 wurde eine neue Grafik-Engine verwendet, die jMonkey-Engine, die immer noch die OpenGL-Basis von HELI-X ist. Seitdem werden OpenGL-Shader unterst\u00fctzt und es gibt realistische Schatten. Die Grafik-Engines vorher waren \u00fcbrigens Java3d (vor 0.9) und dann Xith3D, die leider nicht mehr weiterentwickelt wird. Darum war auch der Umstieg notwendig, und nun gibt es auch seit 2015 ein integriertes Benutzerinterface, das \u00fcbrigens auch in der aktuellen VR-Version verwendet werden kann.<\/p>\n\n\n\n<p>Seit 2015 ist Jan Stauffacher f\u00fcr HELI-X aktiv. Er hat schon sehr viele Modelle und 3d-Szenen f\u00fcr HELI-X erstellt. Von ihm stammen die besten Modelle mit der besten Grafik. Bei Fragen zu Blender ist er mein erster Ansprechpartner. Von ihm stammt \u00fcbrigens auch ein grossartiges Tutorial zur Erstellung von Modellen f\u00fcr HELI-X mit Blender. F\u00fcr jeden Modellbauer ein Muss!<\/p>\n\n\n\n<p>In dieser Zeit entstanden auch einige Demofl\u00fcge von Matthew de Wilde in HELI-X.<\/p>\n\n\n\n<p>Seit Version 8.0, wir sind im Jahr 2018, gibt es Flugzeuge in HELI-X. Ich erinnere mich gerne an die vielen Stunden zur\u00fcck, in denen ich mit Martin Wycisk get\u00fcfftelt habe,um die Flugphysik f\u00fcr Flugzeuge zu implementieren. Wir haben stundenlang das Flachtrudeln angeschaut, und und uns um \u201ehigh angle of Attack\u201c gek\u00fcmmert, also um den \u00dcbergang vom Normalflug \u00fcber das Hovern zum Torquen. Mit Martin optimiere ich immer noch die Aerodynamik von neuen Modellen. Zusammen mit den Flugzeugen entstand auch die M\u00f6glichkeit zum Hangflug mit den entsprechenden Szenen in HELI-X.<\/p>\n\n\n\n<p>Gerne erw\u00e4hne ich auch Michael Peer, der Modelle f\u00fcr HELI-X, z.B. die Whiplash und die Furion 6, modelliert, und Martin M\u00fcnster, der auch wertvolle Inputs zur Flugphysik gibt..<\/p>\n\n\n\n<p>Im Jahr 2019 kam Daniel Wiedemann (<a href=\"https:\/\/www.helischule-gonzalez.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Helischule Gonzalez<\/a>) auf mich zu. Er m\u00f6chte HELI-X f\u00fcr sein Buchprojekt verwenden, und hat mich extremst unterst\u00fctzt, die Pyhsik der Helikopter zu verbessern. F\u00fcr mich ist er ein Ph\u00e4nomen. Im Prinzip kann er alle Figuren blind fliegen und weiss genau, mit welcher Einstellung sich der Helikpter wie verh\u00e4lt. Sein Beitrag ist insbesondere im Autorotationsverhalten der Helikopter in HELI-X zu sp\u00fcren. Nicht umsonst wird gesagt, dass die Autorotationen in HELI-X am realistischsten sind. Mir f\u00e4llt dabei immer wieder ein alter Werbespruch von einer Firma, die ein Finite-Element-Programm herstellt: &#8220;Nature ist non-linear&#8221;, und das gilt noch viel mehr f\u00fcr die Flugpyhsik von 3d-Helikoptern. Daniel bietet \u00fcbrigens eine <a href=\"https:\/\/www.helischule-gonzalez.de\/interview4.0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Online-Flugschule<\/a> zum Helikopterflug an und verwendet dabei HELI-X. Die implementierte Physik scheint also nicht schlecht zu sein &#8230; \ud83d\ude09<\/p>\n\n\n\n<p>Seit Version 9.0 gibt es nun auch hochaufl\u00f6sende Szenen (4K) in HELI-X.<\/p>\n\n\n\n<p><strong>2020-2023:<\/strong><\/p>\n\n\n\n<p>Mit Version 9.1 im Jahr 2020 wurde in HELI-X eine Neuerung implementiert, die es so noch nicht mit einem anderen Flugsimulator gab: Zusammen mit Ulrich R\u00f6hr von Mikado haben wir ein WLAN-Interface entwickelt. So ist es nun mit der VBar Touch m\u00f6glich, den Simulator \u00fcber WLAN zu steuern, ohne Kabel und ohne Interface. Auch die Kn\u00fcppelkonfiguration geschieht dann automatisch.<\/p>\n\n\n\n<p>Mit dieser Version wurde auch das Sound-System verbessert. Die Flexibilit\u00e4t, die hier implementiert ist, wird bisher kaum von den Modellen genutzt. Hier muss ich auch einmal nachbessern. Es gibt so viele M\u00f6glichkeiten!<\/p>\n\n\n\n<p>Nun wurde auch Auggie Copter, den sicher alle von der Facebook-Gruppe RC-Heli Hangout kennen, auf HELI-X aufmerksam. Gemeinsam mit ihm haben wir den &#8220;Auggie\u2019s instinctive training ring&#8221; implemetiert, ein geniales Trainingstool f\u00fcr Piroflips. Daf\u00fcr haben wir einige Stunden per Skype telefoniert und viel diskutiert. Aber das Ergebnis ist prima! Dazu gibt es auch einige Videos von Auggie, die ich auf der Web-Seite verlinkt habe.<\/p>\n\n\n\n<p>Seit dieser Zeit wurde auch Matthijs Amelink aus den Niederlanden f\u00fcr HELI-X aktiv. Von ihm stammen nicht nur hervorragende Szenen in den h\u00f6chsten Aufl\u00f6sungen. Gemeinsam mit ihm wurde auch das &#8220;ready to VR&#8221;-Feature entwickelt: Im VR-Mode sind die Bilder f\u00fcr das linke und rechte Auge unterschiedlich, was mit dem Bild von nur einer Kamera nicht ad\u00e4quat abgebildet werden kann. Und hierf\u00fcr haben wir eine L\u00f6sung entwickelt. Aktuell arbeiten wir an einem HUD speziell f\u00fcr die VR-Version. Hier gehen seine Erfahrungen in Flugsimulatoren ein.<\/p>\n\n\n\n<p>Ein Highlight im M\u00e4rz 2021 war das Online-Training auf dem Mars, mit einer Szene von Matthijs und dem Ingenuity-Helicopter der Mars-Mission von Jan.<\/p>\n\n\n\n<p>Inzwischen ist auch Bj\u00f6rn Hempel sehr f\u00fcr HELI-X engagiert. Er betreibt nicht nur einige der Online-Server, sondern er hat auch den Multiplayer neu implementiert. Mit der Version 10.1 gibt es dann einen Game-Server von ihm. Und auch weitere Features sind in Planung f\u00fcr Version 11, aber mehr wird noch nicht verraten.<\/p>\n\n\n\n<p>Und nun sind wir schon bei der Version 10.0 aus dem Jahr 2021. Hier haben wir ein wichtiges Update der Graphik-Engine realisiert. Als Neuerung gibt es nun einen Virtual-Reality mode (VR), so dass mit 3d-Brillen geflogen werden kann. Mit Physical-Based-Rendering ist eine realistischere Darstellung der Modelle m\u00f6glich (Spiegelungen, Metall-Effekte, etc.). Ausserdem wird der Prozessor M1 von Apple nun nativ unterst\u00fctzt.<\/p>\n\n\n\n<p>Bei mir l\u00e4uft \u00fcbrigens schon die erste Version auf dem Raspberry Pi mit Linux und einem ARM-Prozessor. In der neuesten Version unterst\u00fctzt der Raspberry Pi n\u00e4mlich openGL. Die Version ist noch zu langsam f\u00fcr HELI-X, aber in ein oder zwei Jahren wird das sicher funktionieren!<\/p>\n\n\n\n<p>Und demn\u00e4chst (noch im ersten Quartal 2023) wird HELI-X in der Version 10.1 erscheinen. Dann gibt es eine realistischere Simulation vom Wind, wo die Rauigkeit der Erdoberfl\u00e4che ber\u00fccksichtigt wird. Ausserdem Datail-Verbesserungen wie ein verbessertes Blenden durch die Sonne, oder \u201eMulti Pilot Position Airports\u201c, mit denen es m\u00f6glich sein wird, dass beim Online-Fliegen verschieden Piloten an verschiedenen Positionen stehen.<\/p>\n\n\n\n<p>Gerne pr\u00e4sentierte ich die neue Version 10.1 an der Rotor-Live in Baden-Baden am Stand der Helischule Gonzalez. Ich habe mich gefreut, mit Euch auf 15 Jahre HELI-X anzustossen.<\/p>\n\n\n\n<p>Diese Jahr, also in 2024 wird die Version11 erscheinen mit neuen Features!<\/p>\n\n\n\n<p>Nochmals vielen Dank an alle, die das Projekt unterst\u00fctzt und positiv begleitet haben. Ich freue mich auf die n\u00e4chsten 15 Jahre!<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erst einmal alles Gute im neuen Jahr! Das Jubil\u00e4umsjahr 2023 mit 15 Jahren HELI-X ist zu Ende gegangen. Darum hier nochmal die HELI-X Story in einem St\u00fcck: 2008-2011: Die HELI-X-Story beginnt im Jahr 2007. Bei den Munich Heli Masters wurden erste Kontakte gekn\u00fcpft, und die Idee f\u00fcr den Simulator pr\u00e4sentiert. Hier wurden auch erste Unterst\u00fctzer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-story"],"_links":{"self":[{"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/posts\/981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":1,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"predecessor-version":[{"id":982,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/posts\/981\/revisions\/982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/media\/902"}],"wp:attachment":[{"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heli-x.info\/cms\/de\/wp-json\/wp\/v2\/tags?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}